{"id":7747,"date":"2026-05-12T19:39:09","date_gmt":"2026-05-12T19:39:09","guid":{"rendered":"https:\/\/gioia.lavocedelpaese.info\/?p=7747"},"modified":"2026-05-13T09:29:03","modified_gmt":"2026-05-13T09:29:03","slug":"ritorna-il-consiglio-comunale-con-6-punti-allordine-del-giorno","status":"publish","type":"post","link":"https:\/\/gioia.lavocedelpaese.info\/index.php\/2026\/05\/12\/ritorna-il-consiglio-comunale-con-6-punti-allordine-del-giorno\/","title":{"rendered":"Ritorna il Consiglio Comunale con 6 punti all\u2019ordine del giorno"},"content":{"rendered":"<p style=\"text-align: justify\"><strong><img decoding=\"async\" class=\"size-full wp-image-7749 alignleft\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/05\/26126813151O__OCONVOCAZIONEDELCONSIGLIOCOMUNALE13maggio2026.jpg\" alt=\"\" width=\"400\" height=\"337\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/05\/26126813151O__OCONVOCAZIONEDELCONSIGLIOCOMUNALE13maggio2026.jpg 865w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/05\/26126813151O__OCONVOCAZIONEDELCONSIGLIOCOMUNALE13maggio2026-300x252.jpg 300w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/05\/26126813151O__OCONVOCAZIONEDELCONSIGLIOCOMUNALE13maggio2026-768x646.jpg 768w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\u00c8 stato convocato il Consiglio Comunale<\/strong> di Gioia del Colle, in seduta ordinaria ed in 1^ convocazione, <strong>per il giorno 13 maggio 2026, alle ore 09:30<\/strong> e, nel caso non si raggiunga il numero legale, in 2^ convocazione per il giorno 14 maggio 2026, alle ore 10:30, nella sala consiliare di Palazzo San Domenico, per la trattazione dei<strong> seguenti punti all\u2019ordine del giorno:<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>1<\/strong> &#8211; Riconoscimento del debito fuori bilancio nella causa civile promossa davanti al Giudice di Pace di Bari N. 10444 R.G.;<\/p>\n<p style=\"text-align: justify\"><strong>2<\/strong> &#8211; Riconoscimento del debito fuori bilancio nella causa civile promossa davanti al Giudice di Pace di Bari N. 474\/2026 RG.;<\/p>\n<p style=\"text-align: justify\"><strong>3<\/strong> &#8211; Mozione ex artt. 80 e 84 del Regolamento per il funzionamento del Consiglio comunale avente ad oggetto &#8220;Attivazione di un tavolo tecnico e valutazione di misure correttive dell&#8217;assetto viario e della accessibilit\u00e0 commerciale nell&#8217;area di Piazza Umberto i &#8211; Piazza Plebiscito&#8221;;<\/p>\n<p style=\"text-align: justify\"><strong>4<\/strong> &#8211; Integrazione deliberazione di C.C. n. 63 dell&#8217;1\/09\/2026 &#8211; concessione del titolo di &#8220;citta&#8221;;<\/p>\n<p style=\"text-align: justify\"><strong>5<\/strong> &#8211; Mozione ex art. 84 del Regolamento per il funzionamento del Consiglio comunale avente ad oggetto &#8220;Approvazione delle linee guida per le gare del servizio di mensa scolastica&#8221;;<\/p>\n<p style=\"text-align: justify\"><strong>6<\/strong> &#8211; Approvazione nuovo schema di convenzione con la Centrale unica di committenza presso l&#8217;unione dei comuni &#8220;Montedoro&#8221;. Conferma adesione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 stato convocato il Consiglio Comunale di Gioia del Colle, in seduta ordinaria ed in 1^ convocazione, per il giorno<\/p>\n","protected":false},"author":4,"featured_media":7748,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,33],"tags":[],"class_list":["post-7747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-spalla"],"_links":{"self":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/7747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=7747"}],"version-history":[{"count":1,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/7747\/revisions"}],"predecessor-version":[{"id":7750,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/7747\/revisions\/7750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/7748"}],"wp:attachment":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=7747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=7747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=7747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}