{"id":5616,"date":"2024-12-27T09:45:31","date_gmt":"2024-12-27T09:45:31","guid":{"rendered":"https:\/\/gioia.lavocedelpaese.info\/?p=5616"},"modified":"2025-01-08T13:44:10","modified_gmt":"2025-01-08T13:44:10","slug":"volley-a3-girone-di-ritorno-la-joy-gioia-inizia-con-una-vittoria","status":"publish","type":"post","link":"https:\/\/gioia.lavocedelpaese.info\/index.php\/2024\/12\/27\/volley-a3-girone-di-ritorno-la-joy-gioia-inizia-con-una-vittoria\/","title":{"rendered":"Volley A3 girone di ritorno. La Joy Gioia inizia con una vittoria"},"content":{"rendered":"<p style=\"text-align: justify\"><img decoding=\"async\" class=\"size-full wp-image-5618 alignleft\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/12\/LA-JOY-VOLLEY-FA-SUO-ANCHE-IL-DERBY-DI-RITORNO.jpg\" alt=\"\" width=\"400\" height=\"311\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/12\/LA-JOY-VOLLEY-FA-SUO-ANCHE-IL-DERBY-DI-RITORNO.jpg 1000w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/12\/LA-JOY-VOLLEY-FA-SUO-ANCHE-IL-DERBY-DI-RITORNO-300x233.jpg 300w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/12\/LA-JOY-VOLLEY-FA-SUO-ANCHE-IL-DERBY-DI-RITORNO-768x598.jpg 768w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\u201cLa Joy Volley Gioia del Colle volta subito pagina nel girone Blu, conquistando fra le mura amiche del PalaCapurso l&#8217;importante successo nel derby contro l&#8217;Aurispa Links per la vita Lecce.<br \/>\nCon un convincente 3-1 (25-18, 21-25, 25-15, 25-15) sui salentini, infatti, capitan Mariano e compagni si prendono l&#8217;intera posta in palio, mettendosi alle spalle l&#8217;amaro ko di Modica al tie-break e iniziando nel migliore dei modi la seconda parte della regular season.<\/p>\n<p style=\"text-align: justify\">Tante le indicazioni positive raccolte in serata da coach Sandro Passaro. Su tutte l&#8217;ottima reazione dei biancorossi al secondo set perso, l&#8217;impressionante prestazione sfoggiata a muro (15 punti realizzati nel fondamentale) e la prova da incorniciare del libero<strong> Andrea Di Carlo<\/strong> che, schierato al posto di Pierri (non al meglio delle sue condizioni fisiche) nel secondo set, ha assicurato il suo prezioso contributo alla squadra, meritando il premio di MVP al termine della gara con il 56% di ricezione positiva e con difese e recuperi da applausi.<\/p>\n<p style=\"text-align: justify\">La settima affermazione stagionale proietta i biancorossi a due punti dal secondo posto (occupato attualmente dalla Domotek Reggio Calabria con 23 punti) e carica l&#8217;ambiente Joy Volley in vista del nuovo derby, questa volta fuori casa, contro la BCC Tecbus Castellana Grotte, in programma domenica 29 dicembre.<\/p>\n<p style=\"text-align: justify\"><strong>LA GARA<\/strong><\/p>\n<p style=\"text-align: justify\">La Joy Volley parte subito forte: trascinata da Va\u0161kelis e Cester, la squadra di coach Passaro fissa il punteggio sul momentaneo 11-5. Dall\u2019altra parte della rete, l\u2019Aurispa prova ad accorciare le distanze con Deserio (14-12, muro su Cester) ma si imbatte nella pronta opposizione di Va\u0161kelis e capitan Mariano, artefici del nuovo strappo biancorosso (17-12). Attenta in difesa ed efficace al servizio, la compagine gioiese si invola verso la conquista del primo set (21-14, Cester ancora protagonista), che si materializza sul 25-18 con la pipe potente di Milan.<\/p>\n<p style=\"text-align: justify\">Tornati in campo, a rompere l\u2019iniziale fase di equilibrio del set (6-6) \u00e8 la compagine salentina che, dopo aver perso Fabroni per infortunio, approfitta di alcuni errori in attacco commessi dai biancorossi e si porta sul 7-11 grazie al muro di Deserio su Milan. Con i turni in battuta di Mariano e Cester, la Joy Volley prova a recuperare terreno (13-15, 15-17) sugli avversari che, sul 17-18, piazzano un mini break con Penna e Iannaccone (17-20). Le velleit\u00e0 di rimonta gioiesi si infrangono dinanzi alle grandi difese di Mazzone e Cappio e ai colpi vincenti di Penna e Iannaccone (19-24). Si torna in parit\u00e0 al PalaCapurso (1-1): il secondo set si chiude con l\u2019errore in battuta di Va\u0161kelis (21-25).<br \/>\nLa risposta della Joy Volley non si fa attendere nella terza frazione di gioco: capitan Mariano punge al servizio, Milan va a segno da posto 4 e, dopo un grande recupero di Di Carlo, Cester realizza l\u20198-2. Bravi a respingere i tentativi di rimonta avversari, i gioiesi continuano a brillare nel fondamentale di muro con Persoglia (12-6), portandosi a +8 con un lungolinea imprendibile di Va\u0161kelis (15-7). Gli uomini di coach Passaro spingono forte sull\u2019acceleratore e si danno alla fuga dopo i sigilli di Mariano e Longo (20-10). A chiudere la pratica terzo set ci pensa Persoglia, risoluto a muro su Penna (25-15).<br \/>\nAncora insuperabile a muro con Mariano e Cester e scatenata al servizio con Va\u0161kelis, la Joy Volley controlla il gioco anche nel quarto atto della gara (8-4). L\u2019Aurispa prova a tenere aperta la contesa (14-11) ma cede sotto i colpi di Va\u0161kelis e Cester (18-11). Alla fine il muro di Persoglia su Iannaccone (24-14) e l\u2019errore in attacco di Cimmino (25-15) fanno calare il sipario sul match (25-15)\u201d.<\/p>\n<p style=\"text-align: right\"><strong>Gianluca Falcone<\/strong><\/p>\n<p style=\"text-align: right\">Ufficio Stampa Joy Volley Gioia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa Joy Volley Gioia del Colle volta subito pagina nel girone Blu, conquistando fra le mura amiche del PalaCapurso l&#8217;importante<\/p>\n","protected":false},"author":4,"featured_media":5617,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[7,15],"tags":[],"class_list":["post-5616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regione","category-sport"],"_links":{"self":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/5616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=5616"}],"version-history":[{"count":1,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/5616\/revisions"}],"predecessor-version":[{"id":5619,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/5616\/revisions\/5619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/5617"}],"wp:attachment":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=5616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=5616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=5616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}