{"id":4988,"date":"2024-10-11T19:41:48","date_gmt":"2024-10-11T19:41:48","guid":{"rendered":"https:\/\/gioia.lavocedelpaese.info\/?p=4988"},"modified":"2024-10-22T11:49:25","modified_gmt":"2024-10-22T11:49:25","slug":"famu2024-al-museo-archeologico-nazionale-e-castello-normanno-svevo","status":"publish","type":"post","link":"https:\/\/gioia.lavocedelpaese.info\/index.php\/2024\/10\/11\/famu2024-al-museo-archeologico-nazionale-e-castello-normanno-svevo\/","title":{"rendered":"FAMu2024 al Museo Archeologico Nazionale e Castello Normanno Svevo"},"content":{"rendered":"<p style=\"text-align: justify\"><img decoding=\"async\" class=\"size-full wp-image-4991 alignleft\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/10\/462686275_1137543864580916_5899666656424110853_n-1.jpg\" alt=\"\" width=\"400\" height=\"560\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/10\/462686275_1137543864580916_5899666656424110853_n-1.jpg 571w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/10\/462686275_1137543864580916_5899666656424110853_n-1-214x300.jpg 214w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\u201cAnche quest\u2019anno festeggiamo la Giornata Nazionale delle Famiglie al Museo @FAMu. <strong>Domenica 13 ottobre 2024<\/strong> invitiamo tutte le famiglie a scoprire gli oggetti e le abitudini della vita familiare al tempo dei Peucezi.<\/p>\n<p style=\"text-align: justify\">Ispirandoci al tema scelto per il 2024, <strong>\u201cUn Museo Green\u201d<\/strong>, con materiale di recupero <strong>realizzeremo i giocattoli con cui i bambini si divertivano nell\u2019antica Peucezia<\/strong>.<\/p>\n<p style=\"text-align: justify\">Vi aspettiamo in tanti per trascorrere questa giornata tutti insieme come una grande famiglia. <strong>Attivit\u00e0 per bambini dai 6 ai 12 anni<\/strong> ore: 11:00 &#8211; 16:00 &#8211; 17:30.<\/p>\n<p style=\"text-align: justify\">L\u2019attivit\u00e0 didattica, a <strong>cura del personale Aditus<\/strong>, prevede un costo di \u20ac 8,00 a bambino<\/p>\n<p style=\"text-align: justify\"><strong>\u00c8 consigliata la prenotazione<\/strong> al numero 080 348 13 05.<\/p>\n<p style=\"text-align: justify\">Biglietto d&#8217;ingresso secondo tariffazione ordinaria, con riduzioni per legge e gratuit\u00e0 per i bambini\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAnche quest\u2019anno festeggiamo la Giornata Nazionale delle Famiglie al Museo @FAMu. Domenica 13 ottobre 2024 invitiamo tutte le famiglie a<\/p>\n","protected":false},"author":4,"featured_media":4989,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[6,7],"tags":[],"class_list":["post-4988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","category-regione"],"_links":{"self":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=4988"}],"version-history":[{"count":1,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4988\/revisions"}],"predecessor-version":[{"id":4992,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4988\/revisions\/4992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/4989"}],"wp:attachment":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=4988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=4988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=4988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}