{"id":4408,"date":"2024-07-06T11:07:30","date_gmt":"2024-07-06T11:07:30","guid":{"rendered":"https:\/\/gioia.lavocedelpaese.info\/?p=4408"},"modified":"2024-07-23T16:19:58","modified_gmt":"2024-07-23T16:19:58","slug":"serie-a3-joy-volley-gioia-continua-lopera-di-rafforzamento-della-squadra","status":"publish","type":"post","link":"https:\/\/gioia.lavocedelpaese.info\/index.php\/2024\/07\/06\/serie-a3-joy-volley-gioia-continua-lopera-di-rafforzamento-della-squadra\/","title":{"rendered":"Serie A3. Joy Volley Gioia. Continua l\u2019opera di rafforzamento della squadra"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Confermato il libero Danilo Rinaldi<\/strong><\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" class=\"size-full wp-image-4409 alignleft\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/DANILO-RINALDI-JOY-VOLLEY.jpg\" alt=\"\" width=\"400\" height=\"400\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/DANILO-RINALDI-JOY-VOLLEY.jpg 800w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/DANILO-RINALDI-JOY-VOLLEY-300x300.jpg 300w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/DANILO-RINALDI-JOY-VOLLEY-150x150.jpg 150w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/DANILO-RINALDI-JOY-VOLLEY-768x768.jpg 768w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\u201cC&#8217;\u00e8 ancora la Joy Volley nel futuro di <strong>Danilo Rinaldi<\/strong>. Il libero, originario di Castellana Grotte, rinnova, per un altro anno, il contratto siglato la scorsa estate con la societ\u00e0 del presidente Gianni D&#8217;Elia che, anche nel campionato di serie A3, potr\u00e0 contare sulla sua esperienza, sul suo carisma e sulle sue note doti tecniche.<\/p>\n<p style=\"text-align: justify\">Per l&#8217;atleta trentatreenne, cresciuto nel settore giovanile della Materdomini Volley, si profila cos\u00ec all&#8217;orizzonte il ritorno nella terza categoria nazionale, dove ha ben figurato nella stagione 2022\/2023 con la maglia della Pallavolo Bari.<\/p>\n<p style=\"text-align: justify\">La sua quarta avventura in carriera all&#8217;ombra del Castello normanno-svevo gli dar\u00e0 la possibilit\u00e0 di lavorare con coach Sandro Passaro, suo compagno di squadra a Martina Franca nella stagione 2012\/2013 (in serie B1), e di continuare a competere per traguardi importanti in una piazza a cui si sente fortemente legato\u201d.<\/p>\n<p style=\"text-align: justify\">\u00ab<em>Il desiderio di vincere qualcosa di importante a Gioia del Colle \u00e8 stato uno dei motivi che mi ha spinto a prolungare il contratto con la societ\u00e0<\/em> &#8211; dichiara Danilo Rinaldi -. <em>Sulla mia scelta di restare qui hanno influito anche l&#8217;ottimo rapporto instaurato con il presidente Gianni D&#8217;Elia, l&#8217;opportunit\u00e0 di allenarmi sotto la guida attenta di un allenatore preparato come Sandro Passaro e il forte legame con il pubblico biancorosso. Sono felice di prendere parte ad un progetto sportivo cos\u00ec ambizioso nel pieno della mia maturit\u00e0. Con la mia esperienza e il mio entusiasmo cercher\u00f2 di essere sempre un esempio per tutti<\/em> &#8211; precisa -. <em>La societ\u00e0 sta allestendo una squadra forte e completa in ogni reparto. Sulla carta possiamo ambire a grandi risultati. Il nostro destino, per\u00f2, dipender\u00e0 molto dal lavoro in settimana e dalla capacit\u00e0 del gruppo di reggere la pressione<\/em> &#8211; conclude -. <em>Dovremo affrontare ogni singola gara al massimo delle nostre potenzialit\u00e0. Impegno, umilt\u00e0 e concentrazione non potranno mai mancare in questa stagione, nel corso della quale sar\u00e0 fondamentale il contributo di tutti per arrivare in fondo ad ogni competizione<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify\"><strong>A Gioia Edvinas <\/strong><strong>Va\u0161kelis<\/strong><\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" class=\"size-full wp-image-4410 alignleft\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/449338299_983717333763043_6120105962073908244_n.jpg\" alt=\"\" width=\"400\" height=\"400\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/449338299_983717333763043_6120105962073908244_n.jpg 800w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/449338299_983717333763043_6120105962073908244_n-300x300.jpg 300w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/449338299_983717333763043_6120105962073908244_n-150x150.jpg 150w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/449338299_983717333763043_6120105962073908244_n-768x768.jpg 768w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\u201c\u00c8 l&#8217;opposto lituano Edvinas Va\u0161kelis il nuovo colpo messo a segno dalla Joy Volley Gioia del Colle in vista del prossimo campionato di serie A3.<\/p>\n<p style=\"text-align: justify\">Attivissima sul mercato, la dirigenza biancorossa non si \u00e8 lasciata sfuggire uno degli assoluti protagonisti della terza categoria nazionale negli ultimi tre anni che, con 655 punti totalizzati in 28 gare disputate, ha trascinato la Rinascita Lagonegro al raggiungimento dell&#8217;obiettivo play-off nella scorsa stagione.<\/p>\n<p style=\"text-align: justify\">Accostatosi al mondo del volley all&#8217;et\u00e0 di quindici anni, sin da subito Edvinas mette in mostra le sue importanti qualit\u00e0 e doti tecniche che, in poco tempo, gli consentono di approdare nella massima serie lituana, dove difende i colori della Elga \u0160iauliai e della Flamingo Volley-SM Tauras, e di partecipare a numerose competizioni giovanili di beach volley con la sua nazionale.<\/p>\n<p style=\"text-align: justify\">Dopo le esperienze maturate in Estonia, Belgio, Lituania e Germania con i club Parnnu V\u014drkpalliklubi, Par-ky Menen, TK R\u016bta e Volley Bisons B\u00fchl, per lui si spalancano le porte della serie A3 nella stagione 2021\/2022.<\/p>\n<p style=\"text-align: justify\">In Italia lascia il segno, realizzando 1802 punti in 82 partite disputate con le maglie del Team Volley San Don\u00e0 di Piave, della Farmitalia Catania, dell&#8217;Aurispa Libellula Lecce e, infine, della Rinascita Lagonegro.<\/p>\n<p style=\"text-align: justify\">Pronto a comporre con Peppe Longo una diagonale palleggiatore-opposto da sogno, l&#8217;atleta ventottenne ha gi\u00e0 le idee chiare sugli obiettivi da inseguire nella prossima stagione: \u00ab<em>Sono qui per vincere tutto &#8211; le sue prime parole -. La societ\u00e0 si sta adoperando tanto nella costruzione di un organico forte, dotandolo di tutti i mezzi e delle qualit\u00e0 necessarie per competere su tutti i fronti nel campionato di A3. Dal mese di agosto spetter\u00e0 a noi creare un gruppo solido, unito e motivato, capace di esprimere sempre una qualit\u00e0 di gioco molto alta e una mentalit\u00e0 vincente &#8211; precisa il nuovo opposto della Joy Volley -. In tanti mi hanno parlato di Gioia del Colle, della sua importante storia pallavolistica e della grande passione dei suoi tifosi. Non vedo l&#8217;ora di giocare nella magica atmosfera del PalaCapurso e, a suon di attacchi vincenti, offrire il mio contributo per un campionato di vertice<\/em>\u00bb.[ <strong>foto Aurispa Libellula Lecce<\/strong>]<\/p>\n<p style=\"text-align: justify\"><strong>Chiuso l\u2019accordo con Romolo Mariano<\/strong><\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" class=\"size-full wp-image-4411 alignleft\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/ROMOLO-MARIANO-JOY-VOLLEY.jpg\" alt=\"\" width=\"400\" height=\"400\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/ROMOLO-MARIANO-JOY-VOLLEY.jpg 800w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/ROMOLO-MARIANO-JOY-VOLLEY-300x300.jpg 300w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/ROMOLO-MARIANO-JOY-VOLLEY-150x150.jpg 150w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/ROMOLO-MARIANO-JOY-VOLLEY-768x768.jpg 768w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\u201cLa Joy Volley Gioia del Colle puntella il reparto schiacciatori con l&#8217;ingaggio di un altro atleta di grande esperienza e di sicuro affidamento: <strong>Romolo Mariano<\/strong>.<\/p>\n<p style=\"text-align: justify\">Protagonista per dieci stagioni consecutive in serie A2, il trentaduenne laterale bergamasco accetta l&#8217;ambiziosa sfida in A3 con i colori biancorossi, convinto dalla bont\u00e0 del progetto sportivo della societ\u00e0 presieduta da Gianni D&#8217;Elia e affascinato dall&#8217;opportunit\u00e0 di giocare in una delle piazze storiche del volley pugliese.<\/p>\n<p style=\"text-align: justify\">Cresciuto nel settore giovanile dell&#8217;Olimpia Bergamo, dopo cinque campionati disputati in B1 Romolo approda nella massima serie svizzera, dove vince due scudetti consecutivi con la\u00a0EN Gas&amp;Oil Lugano (dal 2012 al 2014).<\/p>\n<p style=\"text-align: justify\">Nel 2014, a Corigliano, intraprende il suo lungo viaggio in A2, che lo porta a totalizzare ben 2605 punti in 307 gare disputate, a conquistare una promozione in SuperLega con la Globo Banca Popolare del Frusinate Sora (stagione 2015\/2016), a raggiungere due serie finali playoff per la promozione in SuperLega con la Monini Spoleto (perse contro la BCC Castellana Grotte e la Emma Villas Siena, rispettivamente nelle stagioni 2016\/2017 e 2017\/2018) e, infine, dal 2019 ad oggi, a vestire le maglie della Emma Villas Aubay Siena, della Pool Libertas Cant\u00f9, della Delta Group Porto Viro e della Conad Reggio Emilia.<\/p>\n<p style=\"text-align: justify\">\u00ab<em>La chiamata della Joy Volley \u00e8 arrivata nel momento giusto della mia carriera<\/em> &#8211; dichiara il nuovo schiacciatore biancorosso -. <em>Dopo le ultime stagioni in A2 trascorse ad inseguire l&#8217;obiettivo salvezza, ho sentito la necessit\u00e0 di tornare a competere per obiettivi prestigiosi. Per tale ragione non mi sono lasciato sfuggire questa opportunit\u00e0, accettando di buon grado di scendere di categoria. Riportare Gioia del Colle in A2 \u00e8 una mission che mi riempie di stimoli e motivazioni <\/em>&#8211; prosegue -. <em>Abbiamo tutte le potenzialit\u00e0 per realizzare qualcosa di bello e importante. Per riuscirci, per\u00f2, dovremo essere bravi a gestire la pressione e a mantenere il focus sul nostro gioco in ogni singola gara. Profondendo il massimo impegno in allenamento, sono convinto che riusciremo a regalare tante soddisfazioni ai nostri tifosi<\/em>\u00bb.[Foto: <strong>Volley Tricolore Reggio Emilia<\/strong>]<\/p>\n<p style=\"text-align: justify\"><strong>Piervito Disabato. Nuovo rinforzo per il coach Passaro <\/strong><\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" class=\"size-full wp-image-4412 alignleft\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/PIERVITO-DISABATO-JOY-VOLLEY.jpg\" alt=\"\" width=\"400\" height=\"400\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/PIERVITO-DISABATO-JOY-VOLLEY.jpg 800w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/PIERVITO-DISABATO-JOY-VOLLEY-300x300.jpg 300w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/PIERVITO-DISABATO-JOY-VOLLEY-150x150.jpg 150w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/07\/PIERVITO-DISABATO-JOY-VOLLEY-768x768.jpg 768w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\u201cContinua senza sosta il lavoro sul mercato della dirigenza della Joy Volley Gioia del Colle per l&#8217;allestimento del roster 2024\/2025.<\/p>\n<p style=\"text-align: justify\">Alla corte di coach Sandro Passaro approda <strong>Piervito Disabato<\/strong>, talentuoso schiacciatore ventitreenne reduce dall&#8217;ultima stagione nel campionato di serie A3 Credem Banca con la casacca della Shedirpharma Sorrento.<\/p>\n<p style=\"text-align: justify\">Originario di Altamura, dove muove i primi passi nel mondo del volley sotto la guida dell&#8217;allenatore Filippo Capurso, il nuovo laterale biancorosso si afferma nella cantera della Materdominivolley.it Castellana Grotte, vincendo due scudetti (U15 nel 2016 e U16 nel 2017), disputando il suo primo campionato di A2 a soli 15 anni e conquistando la Del Monte\u00ae Junior League \u201cTrofeo Massimo Serenelli\u201d nel 2018.<\/p>\n<p style=\"text-align: justify\">Ai successi collezionati in giallobl\u00f9 si affiancano quelli ottenuti con la maglia azzurra della Nazionale: medaglia d&#8217;oro e premio come migliore schiacciatore della competizione agli Europei U17 disputati in Turchia nel 2017, medaglia d&#8217;oro all&#8217;European Youth Olympic Festival di Baku nel luglio del 2019 e, a distanza di poche settimane, medaglia d&#8217;oro ai Mondiali U19 giocati in Tunisia.<\/p>\n<p style=\"text-align: justify\">Dopo le esperienze maturate in B a Locorotondo e a Taranto, Piervito si affaccia, per la prima volta, in serie A3 nella stagione 2019\/2020, sposando il progetto sportivo della GoldenPlast Civitanova.<\/p>\n<p style=\"text-align: justify\">Nella terza serie nazionale mette in luce tutte le sue qualit\u00e0, trascinando, nelle annate successive, l&#8217;Aurispa Libellula Lecce alla serie dei quarti di finale playoff (persa 2-1 contro la Med Store Macerata), l&#8217;Abba Pineto alla serie finale playoff (persa 2-0 contro la Tinet Prata di Pordenone) e la Farmitalia Catania alla promozione in A2.<\/p>\n<p style=\"text-align: justify\">Adesso \u00e8 pronto a ripetersi con la maglia della Joy Volley: \u00ab<em>Ho scelto Gioia del Colle per la grande tradizione pallavolistica e per l&#8217;ambizioso progetto sportivo illustratomi dal presidente Gianni D&#8217;Elia e dall&#8217;allenatore Sandro Passaro<\/em> &#8211; dichiara lo schiacciatore biancorosso -. <em>Voglio ritagliarmi un ruolo da protagonista in questa nuova avventura. Forte delle esperienze vissute in serie A3, sono pronto a prendermi le mie responsabilit\u00e0 e ad aiutare la squadra a raggiungere gli obiettivi stagionali con la mia grinta e le mie qualit\u00e0 fisiche e tecniche<\/em> &#8211; prosegue -. <em>Ci attende un campionato lungo e difficile, dove sicuramente diremo la nostra. Per affrontarlo al meglio, per\u00f2, dovremo essere bravi a trovare subito la giusta amalgama, sin dalle prime settimane di preparazione. Poi, per puntare a traguardi importanti, sar\u00e0 fondamentale arrivare in condizioni fisiche ottimali al mese di aprile <\/em>&#8211; conclude -. <em>Non vedo l&#8217;ora di respirare il clima partita al PalaCapurso. I tifosi biancorossi sono davvero incredibili. Spero tanto di vivere, insieme a loro, una stagione entusiasmante e ricca di successi<\/em>\u00bb\u201d.[Foto: <strong>Folgore Massa<\/strong>]<\/p>\n<p style=\"text-align: right\"><strong>Gianluca Falcone<\/strong><\/p>\n<p style=\"text-align: right\">Ufficio Stampa Joy Volley Gioia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confermato il libero Danilo Rinaldi \u201cC&#8217;\u00e8 ancora la Joy Volley nel futuro di Danilo Rinaldi. Il libero, originario di Castellana<\/p>\n","protected":false},"author":4,"featured_media":4389,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[7,15],"tags":[],"class_list":["post-4408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regione","category-sport"],"_links":{"self":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=4408"}],"version-history":[{"count":1,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4408\/revisions"}],"predecessor-version":[{"id":4413,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4408\/revisions\/4413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/4389"}],"wp:attachment":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=4408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=4408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=4408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}