{"id":3811,"date":"2024-03-09T13:10:28","date_gmt":"2024-03-09T13:10:28","guid":{"rendered":"https:\/\/gioia.lavocedelpaese.info\/?p=3811"},"modified":"2024-03-16T16:39:56","modified_gmt":"2024-03-16T16:39:56","slug":"muore-in-un-incidente-stradale-il-61enne-gioiese-nino-giordano","status":"publish","type":"post","link":"https:\/\/gioia.lavocedelpaese.info\/index.php\/2024\/03\/09\/muore-in-un-incidente-stradale-il-61enne-gioiese-nino-giordano\/","title":{"rendered":"Muore in un incidente stradale il 61enne gioiese Nino Giordano"},"content":{"rendered":"<p style=\"text-align: justify\"><img decoding=\"async\" class=\"size-full wp-image-3814 alignleft\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/03\/3339304949292824603-1.jpeg\" alt=\"\" width=\"257\" height=\"175\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/03\/3339304949292824603-1.jpeg 257w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/03\/3339304949292824603-1-130x90.jpeg 130w\" sizes=\"(max-width: 257px) 100vw, 257px\" \/>Il gioiese <strong>Nino Giordano<\/strong>, 61enne<strong>, ha perso la vita<\/strong> <strong>questa mattina<\/strong> in un incidente stradale avvenuto <strong>intorno alle 9 nella corsia nord della A14 <\/strong>nel territorio comunale di Faenza. Secondo una prima ricostruzione, il <strong>noto titolare della omonima tabaccheria di via Ricciotto Canudo<\/strong>, per cause ancora da chiarire, <strong>avrebbe perso il controllo della sua auto<\/strong> che, dopo una violenta sbandata, \u00e8 finita fuori strada, impattando violentemente nella scarpata erbosa che affianca la sede stradale. <strong>Nulla da fare per lui, \u00e8 morto sul colpo<\/strong>, era solo a bordo dell&#8217;auto.<\/p>\n<p style=\"text-align: justify\"><strong> <img decoding=\"async\" class=\"size-full wp-image-3815 alignright\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/03\/nino-giordano-incidente.jpg\" alt=\"\" width=\"400\" height=\"290\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/03\/nino-giordano-incidente.jpg 664w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/03\/nino-giordano-incidente-300x218.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>Sul posto sono<\/strong> intervenuti i <strong>Vigili del fuoco<\/strong>, la <strong>Polizia stradale<\/strong>, il <strong>personale di Autostrade<\/strong> per l&#8217;Italia e il <strong>118<\/strong>, <strong>con l&#8217;intervento anche di un elicottero<\/strong>.<\/p>\n<p style=\"text-align: justify\">Per consentire le operazioni di soccorso, si \u00e8 <strong>resa necessaria l&#8217;interruzione temporanea della circolazione<\/strong>. Ma \u00e8 stato tutto inutile, perch\u00e9 l&#8217;uomo \u00e8 stato estratto gi\u00e0 senza vita dal rottame della vettura.(TgR)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il gioiese Nino Giordano, 61enne, ha perso la vita questa mattina in un incidente stradale avvenuto intorno alle 9 nella<\/p>\n","protected":false},"author":4,"featured_media":3812,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[29,7],"tags":[],"class_list":["post-3811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-regione"],"_links":{"self":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/3811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=3811"}],"version-history":[{"count":2,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/3811\/revisions"}],"predecessor-version":[{"id":3817,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/3811\/revisions\/3817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/3812"}],"wp:attachment":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=3811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=3811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=3811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}