{"id":1017,"date":"2023-02-04T10:53:00","date_gmt":"2023-02-04T10:53:00","guid":{"rendered":"https:\/\/gioia.lavocedelpaese.info\/?p=1017"},"modified":"2023-02-10T05:01:30","modified_gmt":"2023-02-10T05:01:30","slug":"travolto-da-auto-pirata-21enne-muore-sulla-statale-100","status":"publish","type":"post","link":"https:\/\/gioia.lavocedelpaese.info\/index.php\/2023\/02\/04\/travolto-da-auto-pirata-21enne-muore-sulla-statale-100\/","title":{"rendered":"Travolto da auto. 21enne muore sulla Statale 100"},"content":{"rendered":"\n<figure class=\"wp-block-image alignleft size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2023\/02\/329003290_716523039861876_1453375545781892086_n.jpg\" alt=\"\" class=\"wp-image-1019\" width=\"400\" height=\"300\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2023\/02\/329003290_716523039861876_1453375545781892086_n.jpg 640w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2023\/02\/329003290_716523039861876_1453375545781892086_n-300x225.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Il tragico incidente \u00e8 avvenuto nella prima mattina di sabato 4 febbraio 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alle 3:30 circa, Mateo Correas, studente universitario spagnolo 21enne, \u00e8 stato investito e ucciso da un&#8217;auto. Il ragazzo non ha avuto scampo. Inutile l\u2019intervento dei sanitari del 118 che nulla hanno potuto se non constatare il decesso del giovane.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sar\u00e0 compito dei Carabinieri della locale Stazione di Casamassima, della Polizia Stradale e dei militari del Nucleo Radio Mobile della Compagnia di Gioia del Colle, intervenuti sul posto, cercare di stabilire le cause e il perch\u00e9 della sua presenza su una arteria cos\u00ec pericolosa per la scarsa visibilit\u00e0, velocit\u00e0 e viabilit\u00e0 sostenuta, e a quell\u2019ora della notte.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2023\/02\/Mateo-Correas-Simon-1024x1024.jpg\" alt=\"\" class=\"wp-image-1061\" width=\"400\" height=\"400\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2023\/02\/Mateo-Correas-Simon-1024x1024.jpg 1024w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2023\/02\/Mateo-Correas-Simon-300x300.jpg 300w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2023\/02\/Mateo-Correas-Simon-150x150.jpg 150w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2023\/02\/Mateo-Correas-Simon-768x768.jpg 768w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2023\/02\/Mateo-Correas-Simon.jpg 800w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La statale, in direzione Bari, \u00e8 rimasta chiusa al transito veicolare fino alle 7:30.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gli operai dell\u2019Anas hanno provveduto a mettere in sicurezza l&#8217;area dove \u00e8 avvenuto l&#8217;omicidio stradale.[foto vivilastrada]<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cIl ragazzo studiava in Belgio con il progetto Erasmus. Era da poco arrivato in Italia per trascorrere qualche giorno di vacanza a casa di un suo amico connazionale, anche lui studente Erasmus presso l\u2019Universit\u00e0 di Bari. Stava partecipando ad una festa in una masseria della zona di Adelfia. Intorno alle 2 di notte potrebbe aver lasciato la festa per tornare a piedi nell\u2019abitazione dell\u2019amico che lo ospitava. Il giovane stava percorrendo un tratto della statale 100 in direzione nord quando \u00e8 stato travolto e ucciso. L\u2019uomo alla guida si \u00e8 subito fermato dopo l\u2019impatto per prestare soccorso. La tragedia ha scosso il mondo dello sport in Spagna. Mateo Correas era un noto giocatore della squadra di pallanuoto Stadium Casablanca di Saragozza\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tragico incidente \u00e8 avvenuto nella prima mattina di sabato 4 febbraio 2023. Alle 3:30 circa, Mateo Correas, studente universitario<\/p>\n","protected":false},"author":4,"featured_media":1018,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[29,30],"tags":[],"class_list":["post-1017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","category-news"],"_links":{"self":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=1017"}],"version-history":[{"count":3,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1017\/revisions"}],"predecessor-version":[{"id":1062,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1017\/revisions\/1062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/1018"}],"wp:attachment":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=1017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=1017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=1017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}