{"id":7443,"date":"2026-02-07T19:57:24","date_gmt":"2026-02-07T19:57:24","guid":{"rendered":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836.jpeg"},"modified":"2026-02-07T19:57:24","modified_gmt":"2026-02-07T19:57:24","slug":"img_2836","status":"inherit","type":"attachment","link":"https:\/\/gioia.lavocedelpaese.info\/index.php\/2026\/02\/07\/88-anniversario-del-36-stormo-alzabandiera-solenne\/img_2836\/","title":{"rendered":"IMG_2836"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false},"class_list":["post-7443","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836.jpeg'><img decoding=\"async\" width=\"280\" height=\"300\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836-280x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836-280x300.jpeg 280w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836.jpeg 746w\" sizes=\"(max-width: 280px) 100vw, 280px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":746,"height":800,"file":"2026\/02\/IMG_2836.jpeg","filesize":88200,"sizes":{"medium":{"file":"IMG_2836-280x300.jpeg","width":280,"height":300,"filesize":19015,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836-280x300.jpeg"},"thumbnail":{"file":"IMG_2836-150x150.jpeg","width":150,"height":150,"filesize":7177,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836-150x150.jpeg"},"colormag-highlighted-post":{"file":"IMG_2836-392x272.jpeg","width":392,"height":272,"filesize":21884,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836-392x272.jpeg"},"colormag-featured-post-medium":{"file":"IMG_2836-390x205.jpeg","width":390,"height":205,"filesize":17144,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836-390x205.jpeg"},"colormag-featured-post-small":{"file":"IMG_2836-130x90.jpeg","width":130,"height":90,"filesize":4234,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836-130x90.jpeg"},"colormag-featured-image":{"file":"IMG_2836-746x445.jpeg","width":746,"height":445,"filesize":55280,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836-746x445.jpeg"},"colormag-default-news":{"file":"IMG_2836-150x150.jpeg","width":150,"height":150,"filesize":7177,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836-150x150.jpeg"},"colormag-featured-image-large":{"file":"IMG_2836-746x600.jpeg","width":746,"height":600,"filesize":71733,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836-746x600.jpeg"},"full":{"file":"IMG_2836.jpeg","width":746,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":7441,"source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/02\/IMG_2836.jpeg","filename":"IMG_2836.jpeg","filesize":88200,"_links":{"self":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/7443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=7443"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":7441,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/7441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}