{"id":4910,"date":"2024-09-26T18:01:37","date_gmt":"2024-09-26T18:01:37","guid":{"rendered":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4.jpg"},"modified":"2024-09-26T18:01:37","modified_gmt":"2024-09-26T18:01:37","slug":"4-4","status":"inherit","type":"attachment","link":"https:\/\/gioia.lavocedelpaese.info\/index.php\/2024\/09\/26\/58-sagra-della-zampina-con-marcella-bella-ivana-spagna-tony-esposito\/4-4\/","title":{"rendered":"4"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-4910","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4.jpg'><img decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4-240x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4-240x300.jpg 240w, https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4.jpg 639w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":639,"height":800,"file":"2024\/09\/4.jpg","filesize":92182,"sizes":{"medium":{"file":"4-240x300.jpg","width":240,"height":300,"filesize":18791,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4-240x300.jpg"},"thumbnail":{"file":"4-150x150.jpg","width":150,"height":150,"filesize":7474,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4-150x150.jpg"},"colormag-highlighted-post":{"file":"4-392x272.jpg","width":392,"height":272,"filesize":30963,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4-392x272.jpg"},"colormag-featured-post-medium":{"file":"4-390x205.jpg","width":390,"height":205,"filesize":23027,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4-390x205.jpg"},"colormag-featured-post-small":{"file":"4-130x90.jpg","width":130,"height":90,"filesize":4127,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4-130x90.jpg"},"colormag-featured-image":{"file":"4-639x445.jpg","width":639,"height":445,"filesize":70061,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4-639x445.jpg"},"colormag-default-news":{"file":"4-150x150.jpg","width":150,"height":150,"filesize":7474,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4-150x150.jpg"},"colormag-featured-image-large":{"file":"4-639x600.jpg","width":639,"height":600,"filesize":89781,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4-639x600.jpg"},"full":{"file":"4.jpg","width":639,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":4902,"source_url":"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2024\/09\/4.jpg","_links":{"self":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/4910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=4910"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":4902,"href":"https:\/\/gioia.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}